{"id":41863,"date":"2018-01-07T08:00:20","date_gmt":"2018-01-07T07:00:20","guid":{"rendered":"https:\/\/prusament.com\/?post_type=prusa_material&#038;p=41863"},"modified":"2022-09-29T10:57:45","modified_gmt":"2022-09-29T08:57:45","slug":"prusament-pa11-nylon-carbon-fiber","status":"publish","type":"prusa_material","link":"https:\/\/prusament.com\/fr\/materials\/prusament-pa11-nylon-carbon-fiber\/","title":{"rendered":"Prusament PA11 (Nylon) Carbon Fiber"},"content":{"rendered":"<p>Parmi les filaments Prusament, le Prusament PA11 Nylon Carbon Fiber a de loin la meilleure r\u00e9sistance aux temp\u00e9ratures et aux produits chimiques. Les pi\u00e8ces imprim\u00e9es supportent jusqu&#8217;\u00e0 190 \u00b0C (selon les contraintes) et ont une r\u00e9sistance accrue \u00e0 de nombreux solvants (NaOH, M\u00e9thanol, Ethanol, Tolu\u00e8ne, Ac\u00e9tone, huiles moteur, benz\u00e8ne, gasoil, etc.).<\/p>\n<p>Le polyamide PA11 est un mat\u00e9riau fabriqu\u00e9 \u00e0 partir d&#8217;huile de ricin, les fibres de carbone utilis\u00e9es pour ce mat\u00e9riau sont recycl\u00e9es, comme pour le Prusament PC Blend Carbon Fiber.<\/p>\n<p>La meilleure utilisation du Prusament PA11Nylon Carbon Fiber est la fabrication de pi\u00e8ces sp\u00e9ciales soumises \u00e0 des contraintes chimiques, m\u00e9caniques et thermiques, telles que des composants de moteur de voiture.<\/p>\n<p>Nous vous recommandons d&#8217;utiliser notre plaque d&#8217;acier PA Nylon pour l&#8217;impression des polyamides, y compris le Prusament PA11 Carbon Fiber. La n\u00e9cessit\u00e9 d&#8217;utiliser une plaque sp\u00e9ciale (ou couche de s\u00e9paration) et une buse en acier tremp\u00e9 rend ce mat\u00e9riau adapt\u00e9 aux utilisateurs avanc\u00e9s.<\/p>\n<p><a href=\"https:\/\/prusament.com\/\/wp-content\/uploads\/2022\/08\/MSDS_PA11CFB-fr.pdf\" target=\"_blank\" rel=\"noopener\">T\u00e9l\u00e9charger la Fiche d\u2019Informations de S\u00e9curit\u00e9 (PDF)<\/a><\/p>\n<h3>Exigences de l&#8217;imprimante<\/h3>\n<table class=\"table\">\n<tbody>\n<tr>\n<th>Plateau<\/th>\n<td>Temp\u00e9rature: 110 \u00b1 10 \u00b0C<br \/>\nUn plateau chauffant est n\u00e9cessaire<br \/>\nEnceinte recommand\u00e9e<\/td>\n<\/tr>\n<tr>\n<th>Surface d&#8217;impression<\/th>\n<td>Plaque \u00e0 effet ressort PA Nylon sp\u00e9ciale nettoy\u00e9e avec de l&#8217;eau propre<\/td>\n<\/tr>\n<tr>\n<th>Extrudeur<\/th>\n<td>Temp\u00e9rature: 285 \u00b1 10 \u00b0C<br \/>\nUne buse en acier tremp\u00e9 est n\u00e9cessaire<\/td>\n<\/tr>\n<tr>\n<th>Refroidissement<\/th>\n<td>Non recommand\u00e9<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Le Prusament PA11 Nylon Carbon Fiber est un filament technique avec une excellente r\u00e9sistance \u00e0 la chaleur, aux produits chimiques et m\u00e9canique. Le mat\u00e9riau est rempli de fibres de carbone pour am\u00e9liorer sa stabilit\u00e9 dimensionnelle. Dans la plupart des param\u00e8tres, il est meilleur que le Prusament PC Blend Carbon Fiber. Il convient \u00e0 la r\u00e9alisation de prototypes dans l&#8217;industrie automobile, l&#8217;a\u00e9ronautique, les hobby, etc.<\/p>\n","protected":false},"featured_media":42037,"menu_order":124,"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/prusament.com\/fr\/wp-json\/wp\/v2\/prusa_material\/41863"}],"collection":[{"href":"https:\/\/prusament.com\/fr\/wp-json\/wp\/v2\/prusa_material"}],"about":[{"href":"https:\/\/prusament.com\/fr\/wp-json\/wp\/v2\/types\/prusa_material"}],"version-history":[{"count":4,"href":"https:\/\/prusament.com\/fr\/wp-json\/wp\/v2\/prusa_material\/41863\/revisions"}],"predecessor-version":[{"id":42022,"href":"https:\/\/prusament.com\/fr\/wp-json\/wp\/v2\/prusa_material\/41863\/revisions\/42022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prusament.com\/fr\/wp-json\/wp\/v2\/media\/42037"}],"wp:attachment":[{"href":"https:\/\/prusament.com\/fr\/wp-json\/wp\/v2\/media?parent=41863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}