{"id":101163,"date":"2025-09-23T17:10:15","date_gmt":"2025-09-23T15:10:15","guid":{"rendered":"https:\/\/prusament.com\/materials\/prusament-pc-space-grade\/"},"modified":"2025-09-25T13:22:56","modified_gmt":"2025-09-25T11:22:56","slug":"prusament-pc-space-grade","status":"publish","type":"prusa_material","link":"https:\/\/prusament.com\/es\/materials\/prusament-pc-space-grade\/","title":{"rendered":"Prusament PC Space Grade"},"content":{"rendered":"<p>Prusament PC Space Grade Black es un material desarrollado para la industria espacial y aplicaciones de f\u00edsica de part\u00edculas. Sus principales ventajas son <b>sus propiedades ESD seguras y su muy baja desgasificaci\u00f3n.<\/b><span style=\"font-weight: 400;\"> Adem\u00e1s, su precio asequible y la facilidad con la que se imprime en impresoras de escritorio comunes lo convierten en un producto \u00fanico en este sector. Gracias a sus excelentes propiedades ESD y su compatibilidad con impresoras 3D de escritorio, es adecuado no solo para piezas expuestas al espacio exterior, sino tambi\u00e9n para proyectos personales avanzados, como carcasas para dispositivos electr\u00f3nicos y mucho m\u00e1s.<\/span><\/p>\n<h3>Material de alta gama al alcance de todos<\/h3>\n<p>Nuestro objetivo era crear un material profesional, pero asequible, que facilitase la creaci\u00f3n de prototipos y la fabricaci\u00f3n de componentes espaciales. Hasta ahora, solo materiales costosos como el PEEK, el PEKK y el PEI con propiedades ESD seguras eran adecuados en este campo. Todos estos materiales requieren impresoras industriales muy caras. El Prusament PC Space Grade Black se puede imprimir en la mayor\u00eda de las impresoras 3D Prusa, lo que reduce significativamente el precio final de los componentes fabricados y aumenta en gran medida la accesibilidad para todos.<\/p>\n<p>El filamento muestra poca o ninguna deformaci\u00f3n. Se pueden imprimir con seguridad <strong>modelos de hasta 200 x 200 mm<\/strong> en impresoras 3D Prusa sin ning\u00fan problema. Es necesario utilizar una boquilla endurecida, ya que los aditivos de carbono son un material muy abrasivo que puede da\u00f1ar las boquillas de lat\u00f3n.<\/p>\n<p><a href=\"https:\/\/storage.googleapis.com\/prusa3d-content-prod-14e8-wordpress-prusament-prod\/2025\/09\/46652829-25_09_23-sds-prusament-pc-space-grade-black-by-prusa-polymers__es.pdf\" target=\"_blank\" rel=\"noopener\">Descarga la Ficha de Datos de Seguridad (PDF)<\/a><\/p>\n<h3>Requisitos de la impresora<\/h3>\n<p>&nbsp;<\/p>\n<table class=\"table\">\n<tbody>\n<tr>\n<th>Boquilla<\/th>\n<td>Temperatura: 290 \u00b1 10 \u00b0C<br \/>\nNecesaria una boquilla endurecida<\/td>\n<\/tr>\n<tr>\n<th>Base Calefactable<\/th>\n<td>Temperatura: 120 \u00b1 10 \u00b0C<\/td>\n<\/tr>\n<tr>\n<th>L\u00e1mina de Impresi\u00f3n Recomendada<\/th>\n<td>Satinada, TXT, PP<\/td>\n<\/tr>\n<tr>\n<th>Cerramiento<\/th>\n<td>No es necesario<\/td>\n<\/tr>\n<tr>\n<th>Perfiles de impresoras 3D compatibles<\/th>\n<td>Prusa Core One, MK4S, XL, Prusa Pro HT90<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h3>Propiedades de disipaci\u00f3n electrost\u00e1tica (ESD)<\/h3>\n<p>Una de las principales caracter\u00edsticas necesarias para su uso en componentes espaciales es la disipaci\u00f3n electrost\u00e1tica. Esta cualidad es importante no solo para los ingenieros espaciales, sino tambi\u00e9n <strong>para cualquiera que trabaje con dispositivos electr\u00f3nicos<\/strong>. En el \u00e1mbito del hobby, los materiales con protecci\u00f3n ESD pueden utilizarse para fabricar carcasas de PC personalizadas y productos similares.<\/p>\n<p>La resistencia medida de los materiales disipativos oscila entre 10<sup>4<\/sup> and 10<sup>11<\/sup> ohmios. Cualquier material con una resistencia superior se considera aislante y cualquier material con valores inferiores se considera conductor.<\/p>\n<p>Hemos medido tanto la resistividad volum\u00e9trica como la resistividad superficial de muestras impresas en 3D con Prusament PC Space Grade Black, y los resultados confirmaron la naturaleza altamente disipativa del material. La resistividad volum\u00e9trica se midi\u00f3 en <strong>2.2\u00d710<sup>4<\/sup> \u03a9\u22c5m<\/strong>, mientras que la resistividad superficial era de <strong>6\u00d710<sup>7<\/sup> \u03a9\/sq<\/strong>. Estos valores excepcionales se obtuvieron directamente de las <strong>muestras impresas en 3D, sin ning\u00fan tipo de posprocesamiento<\/strong>, como el recocido o el lijado, lo que demuestra el rendimiento ESD inherente y constante del filamento. Esto demuestra que las piezas se pueden imprimir y poner en uso inmediatamente para una amplia gama de aplicaciones que requieren una disipaci\u00f3n electrost\u00e1tica fiable.<\/p>\n<h3>Desgasificaci\u00f3n<\/h3>\n<p>Bajo vac\u00edo, los pol\u00edmeros liberan diversos mon\u00f3meros residuales o productos de degradaci\u00f3n polim\u00e9rica. Esto puede afectar, o incluso da\u00f1ar, los componentes electr\u00f3nicos utilizados en el sat\u00e9lite (o cualquier otra maquinaria de precisi\u00f3n). Los gases liberados pueden contaminar los dispositivos \u00f3pticos o provocar mediciones inexactas de los sensores de precisi\u00f3n. Y, por \u00faltimo, la propia liberaci\u00f3n de gas puede disminuir las propiedades f\u00edsicas y mec\u00e1nicas del material. La fabricaci\u00f3n de pol\u00edmeros termopl\u00e1sticos con bajos niveles de desgasificaci\u00f3n es un gran reto, y normalmente se consigue con materiales industriales caros, como el PEKK y el PEEK. Hemos podido cumplir los estrictos requisitos definidos por la Agencia Espacial Europea utilizando PC (policarbonato), que es un material relativamente barato, com\u00fan y f\u00e1cil de imprimir.<\/p>\n<p><strong>Valores de desgasificaci\u00f3n medidos:<\/strong><\/p>\n<p><strong>TML (Total Mass Loss):<\/strong> La p\u00e9rdida de masa se representa como un porcentaje. El l\u00edmite de la ESA es del 1%; el Prusament PC Space Grade Black alcanz\u00f3 el 0.25%.<\/p>\n<p><strong>CVCM (Collected Volatile Condensable Material):<\/strong> El l\u00edmite establecido por la ESA es inferior al 0.1%; el Prusament PC Space Grade Black alcanz\u00f3 un perfecto 0.00%.<\/p>\n<p><strong>RML (Recovered Mass Loss):<\/strong> El l\u00edmite m\u00e1ximo establecido por la ESA es del 1.0%; el Prusament PC Space Grade Black alcanz\u00f3 el 0.12%.<\/p>\n<p>Puedes examinar los resultados y los m\u00e9todos utilizados en nuestro <a href=\"https:\/\/blog.prusa3d.com\/prusament-pc-space-grade-black_121877\" target=\"_blank\" rel=\"noopener\">art\u00edculo de presentaci\u00f3n<\/a> y el <a href=\"https:\/\/storage.googleapis.com\/prusa3d-content-prod-14e8-wordpress-prusament-prod\/2025\/09\/e5f17a69-test-report-tvt2528_prusa.pdf\" target=\"_blank\" rel=\"noopener\">Informe de ensayo emitido por Aerospace &amp; Advanced Composites GmbH<\/a>.<\/p>\n<h3>Propiedades mec\u00e1nicas<\/h3>\n<p>Al inicio de nuestro proyecto conjunto con TRL Space, realizamos una simulaci\u00f3n mediante el m\u00e9todo de elementos finitos para el dise\u00f1o de un CubeSat de una sola unidad y establecimos los valores m\u00ednimos requeridos para las propiedades mec\u00e1nicas que deb\u00edan superar las piezas impresas en 3D. Estos valores m\u00ednimos eran 70 MPa para la resistencia a la tracci\u00f3n, 2 GPa para el m\u00f3dulo de elasticidad, 10 MPa para la adhesi\u00f3n entre capas y 100 \u00b0C para la temperatura de deflexi\u00f3n t\u00e9rmica (HDT).<\/p>\n<p>Nos complace informar que Prusament PC Space Grade Black super\u00f3 con \u00e9xito estos criterios, ya que alcanzamos:<\/p>\n<ul>\n<li>Resistencia a la tracci\u00f3n: <strong>75 MPa<\/strong><\/li>\n<li>M\u00f3dulo de elasticidad: <strong>3.7 GPa<\/strong><\/li>\n<li>Adhesi\u00f3n entre capas: <strong>18 MPa<\/strong><\/li>\n<li>HDT: <strong>137.6 \u00b0C<\/strong> a una carga de 0.45 MPa<\/li>\n<\/ul>\n<p>El hecho de superar estos valores (junto con las propiedades de desgasificaci\u00f3n y de ESD) convierte al filamento en un candidato ideal como material asequible <strong>adecuado para la futura producci\u00f3n de CubeSat.<\/strong> En la Ficha T\u00e9cnica se puede encontrar m\u00e1s informaci\u00f3n sobre las propiedades mec\u00e1nicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prusament PC Space Grade es nuestro filamento de fabricaci\u00f3n propia con una tolerancia de fabricaci\u00f3n de \u00b10.04 mm. El material se ha desarrollado para la industria espacial, aplicaciones de f\u00edsica de part\u00edculas y otros proyectos exigentes. Sus principales ventajas son sus propiedades ESD seguras y su muy baja desgasificaci\u00f3n.<\/p>\n","protected":false},"featured_media":101132,"menu_order":7,"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/prusament.com\/es\/wp-json\/wp\/v2\/prusa_material\/101163"}],"collection":[{"href":"https:\/\/prusament.com\/es\/wp-json\/wp\/v2\/prusa_material"}],"about":[{"href":"https:\/\/prusament.com\/es\/wp-json\/wp\/v2\/types\/prusa_material"}],"version-history":[{"count":4,"href":"https:\/\/prusament.com\/es\/wp-json\/wp\/v2\/prusa_material\/101163\/revisions"}],"predecessor-version":[{"id":101200,"href":"https:\/\/prusament.com\/es\/wp-json\/wp\/v2\/prusa_material\/101163\/revisions\/101200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prusament.com\/es\/wp-json\/wp\/v2\/media\/101132"}],"wp:attachment":[{"href":"https:\/\/prusament.com\/es\/wp-json\/wp\/v2\/media?parent=101163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}